{"id":31635,"date":"2025-04-08T16:25:35","date_gmt":"2025-04-08T14:25:35","guid":{"rendered":"https:\/\/studer-innotec.com\/studer-innotec-sa-gibt-die-uebernahme-des-unternehmens-durch-das-management-bekannt\/"},"modified":"2025-10-06T11:51:25","modified_gmt":"2025-10-06T09:51:25","slug":"studer-innotec-sa-gibt-die-uebernahme-des-unternehmens-durch-das-management-bekannt","status":"publish","type":"post","link":"https:\/\/studer-innotec.com\/de\/studer-innotec-sa-gibt-die-uebernahme-des-unternehmens-durch-das-management-bekannt\/","title":{"rendered":"Studer Innotec SA gibt die \u00dcbernahme des Unternehmens durch das Management bekannt."},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"31635\" class=\"elementor elementor-31635 elementor-26468\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2e091b97 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"2e091b97\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7a7edbf4 sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"7a7edbf4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-55454bd2 sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"55454bd2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><strong>Eine neue Seite f\u00fcr Studer Innotec: Ein motiviertes Team, innovative Produkte und eine verst\u00e4rkte Kundenorientierung.<\/strong><\/h3><p><strong> <\/strong>Die Geschichte von Studer Innotec ist die, eines in einer Garage entstandenen Start-ups, das zu einer unumg\u00e4nglichen Referenz im Bereich von Insel-Wechselrichtern geworden ist. Vor mehr als 37 Jahren von Roland Studer gegr\u00fcndet, beginnt das Unternehmen heute eine neue Etappe, um sein Bestehen zu sichern und seine Zukunft zu gestalten. <\/p><p>Das von gemeinsamem Ehrgeiz getriebene Management hat sich vereint, um in das Kapital zu investieren und das Unternehmen zu \u00fcbernehmen. Dieses kollektive Vorgehen verk\u00f6rpert eine tiefe Motivation, das Erbe von Studer fortzusetzen und den Schwung, der die Geschichte des Unternehmens gepr\u00e4gt hat, weiterzuf\u00fchren. <\/p><p>Diese Dynamik wird von einem neu gegr\u00fcndeten Verwaltungsrat unterst\u00fctzt, der sich aus erfahrenen Pers\u00f6nlichkeiten der Branche zusammensetzt und einen soliden strategischen Rahmen gew\u00e4hrleistet.<\/p><p><em>\u201eMit diesem MBO und den neuen Produkten sind wir bereit, die n\u00e4chste Phase von Studer Innotec anzuf\u00fchren und dabei weiterhin die fortschrittlichen und zuverl\u00e4ssigen L\u00f6sungen zu liefern, die unsere Kunden erwarten.\u201c<\/em> \u2013 Yann Cuenin, Chief Technology Officer und Leiter der Forschungs- und Entwicklungsabteilung bei Studer Innotec.<\/p><p>Studer Innotec blickt im Jahr 2025 entschlossen in die Zukunft mit der Einf\u00fchrung von Flaggschiffprodukten wie dem Off-\/On-Grid Wechselrichter-Ladeger\u00e4t <strong>\n  <a href=\"https:\/\/studer-innotec.com\/next1\" target=\"_blank\" rel=\"noopener\" data-wplink-edit=\"true\">next1<\/a>\n<\/strong> und der Neugestaltung der <strong>\n  <a href=\"https:\/\/studer-innotec.com\/de\/die-eingangsspannung-vom-variotrack-vt65-80-wird-von-150-auf-175vdc-erhoeht\/\" target=\"_blank\" rel=\"noopener\">variotrack<\/a>\n<\/strong> MPPT-Solarladeger\u00e4te. Eine verbesserte App und innovative Schnittstellen werden das Benutzererlebnis bereichern und den \u00dcbergang zu einer erneuerten Produktpalette markieren, die den Erwartungen des Marktes entspricht. <\/p><p>Im Zentrum dieser Transformation bleiben die Kunden die oberste Priorit\u00e4t von Studer Innotec. Mehr denn je verpflichtet sich das Unternehmen, zuverl\u00e4ssige Produkte anzubieten und seine Kunden mit einem pers\u00f6nlichen Service zu begleiten, indem es stets ein offenes Ohr f\u00fcr ihre Bed\u00fcrfnisse hat. <\/p><p>Studer Innotec schreibt heute eine neue Seite seiner Geschichte, die von einem dynamischen Team, zukunftsorientierten Produkten und einer vertrauensvollen Kundenbeziehung getragen wird.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-10d02cd sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"10d02cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d334110 sc_fly_static elementor-widget elementor-widget-image\" data-id=\"d334110\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/studer-innotec.com\/wp-content\/uploads\/2025\/05\/MBO-Studer-Innotec-SA-scaled.png\" title=\"\" alt=\"MBO Studer Innotec SA\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Von rechts nach links: Gr\u00fcnder Roland Studer und die \u00dcbernehmer: Moix Pierre-Olivier, Remy Serge, R\u00e9mondeulaz C\u00e9line, Cuenin Yann.<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Eine neue Seite f\u00fcr Studer Innotec: Ein motiviertes Team, innovative Produkte und eine verst\u00e4rkte Kundenorientierung. Die Geschichte von Studer Innotec ist die, eines in einer Garage entstandenen Start-ups, das zu&hellip;<\/p>\n","protected":false},"author":3,"featured_media":38201,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[292],"tags":[],"class_list":["post-31635","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Studer Innotec SA gibt die \u00dcbernahme des Unternehmens durch das Management bekannt. - Studer Innotec<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/studer-innotec.com\/de\/studer-innotec-sa-gibt-die-uebernahme-des-unternehmens-durch-das-management-bekannt\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Studer Innotec SA gibt die \u00dcbernahme des Unternehmens durch das Management bekannt. - Studer Innotec\" \/>\n<meta property=\"og:description\" content=\"Eine neue Seite f\u00fcr Studer Innotec: Ein motiviertes Team, innovative Produkte und eine verst\u00e4rkte Kundenorientierung. Die Geschichte von Studer Innotec ist die, eines in einer Garage entstandenen Start-ups, das zu&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/studer-innotec.com\/de\/studer-innotec-sa-gibt-die-uebernahme-des-unternehmens-durch-das-management-bekannt\/\" \/>\n<meta property=\"og:site_name\" content=\"Studer Innotec\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/StuderInnotec\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-08T14:25:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-06T09:51:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/studer-innotec.com\/wp-content\/uploads\/2025\/05\/MBO-Studer-Innotec-SA-1024x681.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"681\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Sacha\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sacha\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/studer-innotec.com\\\/de\\\/studer-innotec-sa-gibt-die-uebernahme-des-unternehmens-durch-das-management-bekannt\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/studer-innotec.com\\\/de\\\/studer-innotec-sa-gibt-die-uebernahme-des-unternehmens-durch-das-management-bekannt\\\/\"},\"author\":{\"name\":\"Sacha\",\"@id\":\"https:\\\/\\\/studer-innotec.com\\\/de\\\/#\\\/schema\\\/person\\\/70269c00079329c7f06dcc06b9968f44\"},\"headline\":\"Studer Innotec SA gibt die \u00dcbernahme des Unternehmens durch das Management bekannt.\",\"datePublished\":\"2025-04-08T14:25:35+00:00\",\"dateModified\":\"2025-10-06T09:51:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/studer-innotec.com\\\/de\\\/studer-innotec-sa-gibt-die-uebernahme-des-unternehmens-durch-das-management-bekannt\\\/\"},\"wordCount\":345,\"publisher\":{\"@id\":\"https:\\\/\\\/studer-innotec.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/studer-innotec.com\\\/de\\\/studer-innotec-sa-gibt-die-uebernahme-des-unternehmens-durch-das-management-bekannt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/studer-innotec.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/MBO-Studer-Innotec-SA.png\",\"articleSection\":[\"News\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/studer-innotec.com\\\/de\\\/studer-innotec-sa-gibt-die-uebernahme-des-unternehmens-durch-das-management-bekannt\\\/\",\"url\":\"https:\\\/\\\/studer-innotec.com\\\/de\\\/studer-innotec-sa-gibt-die-uebernahme-des-unternehmens-durch-das-management-bekannt\\\/\",\"name\":\"Studer Innotec SA gibt die \u00dcbernahme des Unternehmens durch das Management bekannt. - Studer Innotec\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/studer-innotec.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/studer-innotec.com\\\/de\\\/studer-innotec-sa-gibt-die-uebernahme-des-unternehmens-durch-das-management-bekannt\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/studer-innotec.com\\\/de\\\/studer-innotec-sa-gibt-die-uebernahme-des-unternehmens-durch-das-management-bekannt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/studer-innotec.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/MBO-Studer-Innotec-SA.png\",\"datePublished\":\"2025-04-08T14:25:35+00:00\",\"dateModified\":\"2025-10-06T09:51:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/studer-innotec.com\\\/de\\\/studer-innotec-sa-gibt-die-uebernahme-des-unternehmens-durch-das-management-bekannt\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/studer-innotec.com\\\/de\\\/studer-innotec-sa-gibt-die-uebernahme-des-unternehmens-durch-das-management-bekannt\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/studer-innotec.com\\\/de\\\/studer-innotec-sa-gibt-die-uebernahme-des-unternehmens-durch-das-management-bekannt\\\/#primaryimage\",\"url\":\"https:\\\/\\\/studer-innotec.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/MBO-Studer-Innotec-SA.png\",\"contentUrl\":\"https:\\\/\\\/studer-innotec.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/MBO-Studer-Innotec-SA.png\",\"width\":2560,\"height\":1703,\"caption\":\"MBO Studer Innotec SA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/studer-innotec.com\\\/de\\\/studer-innotec-sa-gibt-die-uebernahme-des-unternehmens-durch-das-management-bekannt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/studer-innotec.com\\\/de\\\/startseite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Studer Innotec SA gibt die \u00dcbernahme des Unternehmens durch das Management bekannt.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/studer-innotec.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/studer-innotec.com\\\/de\\\/\",\"name\":\"Studer Innotec\",\"description\":\"Leader in offgrid power management\",\"publisher\":{\"@id\":\"https:\\\/\\\/studer-innotec.com\\\/de\\\/#organization\"},\"alternateName\":\"Studer Innotec\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/studer-innotec.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/studer-innotec.com\\\/de\\\/#organization\",\"name\":\"Studer Innotec\",\"alternateName\":\"Studer Innotec\",\"url\":\"https:\\\/\\\/studer-innotec.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/studer-innotec.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/studer-innotec.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/logo-studer-noir-1.png\",\"contentUrl\":\"https:\\\/\\\/studer-innotec.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/logo-studer-noir-1.png\",\"width\":182,\"height\":98,\"caption\":\"Studer Innotec\"},\"image\":{\"@id\":\"https:\\\/\\\/studer-innotec.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/StuderInnotec\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/studer-innotec\\\/\",\"https:\\\/\\\/www.instagram.com\\\/studerinnotec\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCVV4mlwSrtnFWSbE6iIFRBg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/studer-innotec.com\\\/de\\\/#\\\/schema\\\/person\\\/70269c00079329c7f06dcc06b9968f44\",\"name\":\"Sacha\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Studer Innotec SA gibt die \u00dcbernahme des Unternehmens durch das Management bekannt. - Studer Innotec","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/studer-innotec.com\/de\/studer-innotec-sa-gibt-die-uebernahme-des-unternehmens-durch-das-management-bekannt\/","og_locale":"de_DE","og_type":"article","og_title":"Studer Innotec SA gibt die \u00dcbernahme des Unternehmens durch das Management bekannt. - Studer Innotec","og_description":"Eine neue Seite f\u00fcr Studer Innotec: Ein motiviertes Team, innovative Produkte und eine verst\u00e4rkte Kundenorientierung. Die Geschichte von Studer Innotec ist die, eines in einer Garage entstandenen Start-ups, das zu&hellip;","og_url":"https:\/\/studer-innotec.com\/de\/studer-innotec-sa-gibt-die-uebernahme-des-unternehmens-durch-das-management-bekannt\/","og_site_name":"Studer Innotec","article_publisher":"https:\/\/www.facebook.com\/StuderInnotec","article_published_time":"2025-04-08T14:25:35+00:00","article_modified_time":"2025-10-06T09:51:25+00:00","og_image":[{"width":1024,"height":681,"url":"https:\/\/studer-innotec.com\/wp-content\/uploads\/2025\/05\/MBO-Studer-Innotec-SA-1024x681.png","type":"image\/png"}],"author":"Sacha","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Sacha","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/studer-innotec.com\/de\/studer-innotec-sa-gibt-die-uebernahme-des-unternehmens-durch-das-management-bekannt\/#article","isPartOf":{"@id":"https:\/\/studer-innotec.com\/de\/studer-innotec-sa-gibt-die-uebernahme-des-unternehmens-durch-das-management-bekannt\/"},"author":{"name":"Sacha","@id":"https:\/\/studer-innotec.com\/de\/#\/schema\/person\/70269c00079329c7f06dcc06b9968f44"},"headline":"Studer Innotec SA gibt die \u00dcbernahme des Unternehmens durch das Management bekannt.","datePublished":"2025-04-08T14:25:35+00:00","dateModified":"2025-10-06T09:51:25+00:00","mainEntityOfPage":{"@id":"https:\/\/studer-innotec.com\/de\/studer-innotec-sa-gibt-die-uebernahme-des-unternehmens-durch-das-management-bekannt\/"},"wordCount":345,"publisher":{"@id":"https:\/\/studer-innotec.com\/de\/#organization"},"image":{"@id":"https:\/\/studer-innotec.com\/de\/studer-innotec-sa-gibt-die-uebernahme-des-unternehmens-durch-das-management-bekannt\/#primaryimage"},"thumbnailUrl":"https:\/\/studer-innotec.com\/wp-content\/uploads\/2025\/05\/MBO-Studer-Innotec-SA.png","articleSection":["News"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/studer-innotec.com\/de\/studer-innotec-sa-gibt-die-uebernahme-des-unternehmens-durch-das-management-bekannt\/","url":"https:\/\/studer-innotec.com\/de\/studer-innotec-sa-gibt-die-uebernahme-des-unternehmens-durch-das-management-bekannt\/","name":"Studer Innotec SA gibt die \u00dcbernahme des Unternehmens durch das Management bekannt. - Studer Innotec","isPartOf":{"@id":"https:\/\/studer-innotec.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/studer-innotec.com\/de\/studer-innotec-sa-gibt-die-uebernahme-des-unternehmens-durch-das-management-bekannt\/#primaryimage"},"image":{"@id":"https:\/\/studer-innotec.com\/de\/studer-innotec-sa-gibt-die-uebernahme-des-unternehmens-durch-das-management-bekannt\/#primaryimage"},"thumbnailUrl":"https:\/\/studer-innotec.com\/wp-content\/uploads\/2025\/05\/MBO-Studer-Innotec-SA.png","datePublished":"2025-04-08T14:25:35+00:00","dateModified":"2025-10-06T09:51:25+00:00","breadcrumb":{"@id":"https:\/\/studer-innotec.com\/de\/studer-innotec-sa-gibt-die-uebernahme-des-unternehmens-durch-das-management-bekannt\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/studer-innotec.com\/de\/studer-innotec-sa-gibt-die-uebernahme-des-unternehmens-durch-das-management-bekannt\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/studer-innotec.com\/de\/studer-innotec-sa-gibt-die-uebernahme-des-unternehmens-durch-das-management-bekannt\/#primaryimage","url":"https:\/\/studer-innotec.com\/wp-content\/uploads\/2025\/05\/MBO-Studer-Innotec-SA.png","contentUrl":"https:\/\/studer-innotec.com\/wp-content\/uploads\/2025\/05\/MBO-Studer-Innotec-SA.png","width":2560,"height":1703,"caption":"MBO Studer Innotec SA"},{"@type":"BreadcrumbList","@id":"https:\/\/studer-innotec.com\/de\/studer-innotec-sa-gibt-die-uebernahme-des-unternehmens-durch-das-management-bekannt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/studer-innotec.com\/de\/startseite\/"},{"@type":"ListItem","position":2,"name":"Studer Innotec SA gibt die \u00dcbernahme des Unternehmens durch das Management bekannt."}]},{"@type":"WebSite","@id":"https:\/\/studer-innotec.com\/de\/#website","url":"https:\/\/studer-innotec.com\/de\/","name":"Studer Innotec","description":"Leader in offgrid power management","publisher":{"@id":"https:\/\/studer-innotec.com\/de\/#organization"},"alternateName":"Studer Innotec","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/studer-innotec.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/studer-innotec.com\/de\/#organization","name":"Studer Innotec","alternateName":"Studer Innotec","url":"https:\/\/studer-innotec.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/studer-innotec.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/studer-innotec.com\/wp-content\/uploads\/2024\/06\/logo-studer-noir-1.png","contentUrl":"https:\/\/studer-innotec.com\/wp-content\/uploads\/2024\/06\/logo-studer-noir-1.png","width":182,"height":98,"caption":"Studer Innotec"},"image":{"@id":"https:\/\/studer-innotec.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/StuderInnotec","https:\/\/www.linkedin.com\/company\/studer-innotec\/","https:\/\/www.instagram.com\/studerinnotec\/","https:\/\/www.youtube.com\/channel\/UCVV4mlwSrtnFWSbE6iIFRBg"]},{"@type":"Person","@id":"https:\/\/studer-innotec.com\/de\/#\/schema\/person\/70269c00079329c7f06dcc06b9968f44","name":"Sacha"}]}},"_links":{"self":[{"href":"https:\/\/studer-innotec.com\/de\/wp-json\/wp\/v2\/posts\/31635","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/studer-innotec.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/studer-innotec.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/studer-innotec.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/studer-innotec.com\/de\/wp-json\/wp\/v2\/comments?post=31635"}],"version-history":[{"count":2,"href":"https:\/\/studer-innotec.com\/de\/wp-json\/wp\/v2\/posts\/31635\/revisions"}],"predecessor-version":[{"id":31650,"href":"https:\/\/studer-innotec.com\/de\/wp-json\/wp\/v2\/posts\/31635\/revisions\/31650"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/studer-innotec.com\/de\/wp-json\/wp\/v2\/media\/38201"}],"wp:attachment":[{"href":"https:\/\/studer-innotec.com\/de\/wp-json\/wp\/v2\/media?parent=31635"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/studer-innotec.com\/de\/wp-json\/wp\/v2\/categories?post=31635"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/studer-innotec.com\/de\/wp-json\/wp\/v2\/tags?post=31635"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}